{"id":546,"date":"2023-09-06T13:47:16","date_gmt":"2023-09-06T16:47:16","guid":{"rendered":"https:\/\/estiloclassico.com.br\/index.php\/product\/cadeira-estilo-chines-ii\/"},"modified":"2023-10-11T17:06:57","modified_gmt":"2023-10-11T20:06:57","slug":"cadeira-estilo-chines-ii","status":"publish","type":"product","link":"https:\/\/estiloclassico.com.br\/index.php\/product\/cadeira-estilo-chines-ii\/","title":{"rendered":"Cadeira estilo chin\u00eas II"},"content":{"rendered":"<p>Cadeira estilo chin\u00eas II em mogno.<br \/>\nAssento forrado em tecido.<\/p>\n<p>A:75cm<br \/>\nL:64cm<br \/>\nC:54cm<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cadeira estilo chin\u00eas II em mogno. Assento forrado em tecido. A:75cm L:64cm C:54cm<\/p>\n","protected":false},"featured_media":343,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set"},"product_cat":[18],"product_tag":[],"_links":{"self":[{"href":"https:\/\/estiloclassico.com.br\/index.php\/wp-json\/wp\/v2\/product\/546"}],"collection":[{"href":"https:\/\/estiloclassico.com.br\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/estiloclassico.com.br\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/estiloclassico.com.br\/index.php\/wp-json\/wp\/v2\/media\/343"}],"wp:attachment":[{"href":"https:\/\/estiloclassico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=546"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/estiloclassico.com.br\/index.php\/wp-json\/wp\/v2\/product_cat?post=546"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/estiloclassico.com.br\/index.php\/wp-json\/wp\/v2\/product_tag?post=546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}