{"id":551,"date":"2023-09-06T13:47:21","date_gmt":"2023-09-06T16:47:21","guid":{"rendered":"https:\/\/estiloclassico.com.br\/index.php\/product\/cadeira-estilo-ingles-com-bracos-iii\/"},"modified":"2023-10-11T17:06:50","modified_gmt":"2023-10-11T20:06:50","slug":"cadeira-estilo-ingles-com-bracos-iii","status":"publish","type":"product","link":"https:\/\/estiloclassico.com.br\/index.php\/product\/cadeira-estilo-ingles-com-bracos-iii\/","title":{"rendered":"Cadeira estilo ingl\u00eas com bra\u00e7os III"},"content":{"rendered":"<p>Cadeira em mogno com bra\u00e7os, estilo ingl\u00eas. Forrada em couro ou em tecido fornecido pelo cliente.<\/p>\n<p>A:79cm<br \/>\nL:47cm<br \/>\nP:46cm<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cadeira em mogno com bra\u00e7os, estilo ingl\u00eas. Forrada em couro ou em tecido fornecido pelo cliente. A:79cm L:47cm P:46cm<\/p>\n","protected":false},"featured_media":351,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set"},"product_cat":[18],"product_tag":[],"_links":{"self":[{"href":"https:\/\/estiloclassico.com.br\/index.php\/wp-json\/wp\/v2\/product\/551"}],"collection":[{"href":"https:\/\/estiloclassico.com.br\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/estiloclassico.com.br\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/estiloclassico.com.br\/index.php\/wp-json\/wp\/v2\/media\/351"}],"wp:attachment":[{"href":"https:\/\/estiloclassico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=551"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/estiloclassico.com.br\/index.php\/wp-json\/wp\/v2\/product_cat?post=551"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/estiloclassico.com.br\/index.php\/wp-json\/wp\/v2\/product_tag?post=551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}